{"id":1793,"date":"2010-05-02T21:20:27","date_gmt":"2010-05-02T20:20:27","guid":{"rendered":"http:\/\/www.comiteactionpalestine.org\/word\/?p=1793"},"modified":"2014-04-27T21:22:21","modified_gmt":"2014-04-27T20:22:21","slug":"soiree-debat-la-palestine-et-les-enjeux-geopolitiques-au-moyen-orient","status":"publish","type":"post","link":"https:\/\/www.comiteactionpalestine.org\/word\/soiree-debat-la-palestine-et-les-enjeux-geopolitiques-au-moyen-orient\/","title":{"rendered":"Soir\u00e9e D\u00e9bat : La Palestine et les enjeux g\u00e9opolitiques au Moyen-Orient"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1793?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\" \/><\/a><a href=\"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1793?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><p style=\"color: #464646\" align=\"center\"><span style=\"font-size: large\"><strong>En m\u00e9moire de la\u00a0<\/strong><strong>NAKBA<\/strong><\/span><\/p>\n<p style=\"color: #464646\" align=\"center\"><em><br \/>\nLa cr\u00e9ation de l\u2019Etat d\u2019Isra\u00ebl, le 14 mai 1948,<br \/>\n<\/em><em>c\u2019est la Catastrophe, la Nakba pour les Palestiniens.<\/em><\/p>\n<p style=\"color: #464646\" align=\"center\"><strong><span style=\"font-size: large\"><br \/>\nLe\u00a0<span style=\"color: #ff0000\">COMITE<\/span>\u00a0ACTION\u00a0<span style=\"color: #009900\">PALESTINE<\/span><\/span><\/strong><\/p>\n<p style=\"color: #464646\" align=\"center\"><strong>vous invite \u00e0 une soir\u00e9e-d\u00e9bat<\/p>\n<p><\/strong><\/p>\n<p style=\"color: #464646\" align=\"center\"><strong><span style=\"font-size: x-large\">La Palestine<\/span><\/strong><\/p>\n<p style=\"color: #464646\" align=\"center\"><strong><span style=\"font-size: x-large\">et les enjeux g\u00e9opolitiques au<\/span><\/strong><\/p>\n<p style=\"color: #464646\" align=\"center\"><strong><span style=\"font-size: x-large\">Moyen-Orient<\/span><\/p>\n<p><\/strong><\/p>\n<p style=\"color: #464646\" align=\"center\"><span style=\"color: #ff0000;font-size: large\"><strong>Le vendredi 14 mai \u00e0 20h30<\/strong><\/span><\/p>\n<p style=\"color: #464646\" align=\"center\"><strong>Ath\u00e9n\u00e9e Municipal, place St Christoly, Bordeaux<br \/>\n<\/strong>(Tram A et B, arr\u00eat H\u00f4tel de Ville)<\/p>\n<p style=\"color: #464646\" align=\"center\"><strong>avec<\/strong><\/p>\n<p style=\"color: #464646\" align=\"center\"><strong>&#8211;\u00a0<span style=\"font-size: large\">Mohammed TAHAR BENSAADA<\/span>,\u00a0<\/strong>professeur de sciences sociales<\/p>\n<p style=\"color: #464646\" align=\"center\"><strong>\u00ab\u00a0<em>La r\u00e9sistance palestinienne et les enjeux g\u00e9opolitiques au Moyen-Orient<\/em>\u00a0\u00bb<\/p>\n<p><\/strong><\/p>\n<p style=\"color: #464646\" align=\"center\">&#8211;\u00a0<strong><span style=\"font-size: large\">Recai USTA<\/span>,\u00a0<\/strong>pr\u00e9sident de l\u2019AMGT<\/p>\n<p style=\"color: #464646\" align=\"center\"><strong>\u00ab\u00a0<em>Le changement politique en Turquie : un tournant au Moyen-Orient<\/em>\u00a0\u00bb<\/strong><\/p>\n<p style=\"color: #464646\">\n<p style=\"color: #464646\" align=\"justify\"><strong><em>Le 15 mai 1948 : avec la cr\u00e9ation de l\u2019Etat-colonie Isra\u00ebl, la Palestine est ray\u00e9e de la carte et une grande partie du peuple palestinien est contrainte \u00e0 l\u2019exil lors d\u2019une vaste op\u00e9ration d\u2019\u00e9puration ethnique. Plus de 500 villages sont d\u00e9truits et pr\u00e8s de 800 000 Palestiniens expuls\u00e9s de leur terre. De nombreux massacres ont lieu.\u00a0<\/em><\/strong><strong><em>Mais 60 ans apr\u00e8s, le peuple Palestinien r\u00e9siste plus que jamais \u00e0 la plus terrible des colonisations, \u00e0 l\u2019\u00e9puration ethnique qui se poursuit et au r\u00e9gime d\u2019apartheid instaur\u00e9 par l\u2019Etat isra\u00e9lien raciste.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En m\u00e9moire de la\u00a0NAKBA La cr\u00e9ation de l\u2019Etat d\u2019Isra\u00ebl, le 14 mai 1948, c\u2019est la Catastrophe, la Nakba pour les Palestiniens. Le\u00a0COMITE\u00a0ACTION\u00a0PALESTINE vous invite \u00e0 une soir\u00e9e-d\u00e9bat La Palestine et les enjeux g\u00e9opolitiques au Moyen-Orient Le vendredi 14 mai \u00e0 20h30 Ath\u00e9n\u00e9e Municipal, place St Christoly, Bordeaux (Tram A et B, arr\u00eat H\u00f4tel de Ville) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actions"],"views":2520,"_links":{"self":[{"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/comments?post=1793"}],"version-history":[{"count":1,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1793\/revisions"}],"predecessor-version":[{"id":1796,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1793\/revisions\/1796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/media\/1372"}],"wp:attachment":[{"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/media?parent=1793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/categories?post=1793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/tags?post=1793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}