{"id":1622,"date":"2012-03-10T21:03:42","date_gmt":"2012-03-10T20:03:42","guid":{"rendered":"http:\/\/www.comiteactionpalestine.org\/word\/?p=1622"},"modified":"2014-04-24T21:08:05","modified_gmt":"2014-04-24T20:08:05","slug":"resister-au-sionisme","status":"publish","type":"post","link":"https:\/\/www.comiteactionpalestine.org\/word\/resister-au-sionisme\/","title":{"rendered":"R\u00e9sister au sionisme"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1622?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\" \/><\/a><a href=\"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1622?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><p style=\"text-align: center\"><strong>Comit\u00e9<\/strong><strong>\u00a0<\/strong><strong>Action<\/strong><strong>\u00a0<\/strong><strong>Palestine<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><strong>A l\u2019occasion de la Journ\u00e9e de la terre\u00a0<\/strong><strong>en Palestine,<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><strong>\u00ab\u00a0R\u00e9sister au sionisme\u00a0\u00bb<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>Conf\u00e9rences-d\u00e9bats<\/strong><\/p>\n<p style=\"text-align: center\"><strong>avec<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><strong>Jean Bricmont,<\/strong><\/p>\n<p style=\"text-align: center\">\u00a0\u00ab\u00a0R\u00e9sister au sionisme : d\u00e9fendre la libert\u00e9 d&rsquo;expression\u00a0\u00bb<\/p>\n<p style=\"text-align: center\"><strong>le 23 mars 20h30, Ath\u00e9n\u00e9e Municipal, Bordeaux<\/strong><\/p>\n<p style=\"text-align: center\"><strong>(Tram A et B, arr\u00eat H\u00f4tel de Ville)<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>Omar Mazri,<\/strong><\/p>\n<p style=\"text-align: center\">\u00a0\u00ab\u00a0R\u00e9volutions et<br \/>\ncontre-r\u00e9volution dans le monde arabe\u00a0\u00bb<\/p>\n<p style=\"text-align: center\"><strong>le 29 mars 20h30, salle Condorcet, Lormont<\/strong><\/p>\n<p style=\"text-align: center\"><strong>(Tram A, direction Bassens-Carbon blanc,\u00a0arr\u00eat Gravi\u00e8res)<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>La Journ\u00e9e de la Terre est hautement symbolique : elle exprime \u00e0 la fois la r\u00e9sistance au sionisme et le refus de l\u2019usurpation de la terre qui est l\u2019essence-m\u00eame de la colonisation juive de la Palestine.<\/strong><\/p>\n<p style=\"text-align: justify\">Le sionisme est un mouvement colonial et raciste qui est \u00e0 l\u2019origine de la cr\u00e9ation de l\u2019Etat d\u2019Isra\u00ebl. Celui-ci b\u00e9n\u00e9ficie du soutien inconditionnel des puissances imp\u00e9rialistes occidentales qui consid\u00e8rent cette entit\u00e9 comme leur agent au Proche et Moyen Orient. Depuis plus d\u2019un si\u00e8cle, les Palestiniens connaissent le prix de leur r\u00e9sistance au sionisme.<\/p>\n<p style=\"text-align: justify\">Le 30 mars 1976, six Palestiniens de 1948 (c&rsquo;est-\u00e0-dire ceux qui ont pu rester en 1948 apr\u00e8s la cr\u00e9ation par la force de l\u2019Etat d\u2019Isra\u00ebl) \u00e9taient abattus par l\u2019arm\u00e9e d\u2019occupation d\u2019Isra\u00ebl, 96 \u00e9taient bless\u00e9s et 300 autres arr\u00eat\u00e9s. Leur crime ? Avoir manifest\u00e9 contre l\u2019\u00c9tat sioniste qui avait confisqu\u00e9 et d\u00e9clar\u00e9 \u201c zone militaire \u201d 1700 hectares appartenant \u00e0 des villages palestiniens. Depuis lors, tous les 30 mars, la \u00ab Journ\u00e9e de la Terre \u00bb comm\u00e9more cet \u00e9v\u00e9nement en Palestine et partout dans le monde o\u00f9 se trouvent les d\u00e9fenseurs des droits du peuple palestinien.<\/p>\n<p style=\"text-align: justify\">Pour prot\u00e9ger Isra\u00ebl et ses int\u00e9r\u00eats, l\u2019imp\u00e9rialisme n\u2019h\u00e9site pas \u00e0 mettre \u00e0 feu et \u00e0 sang toute cette r\u00e9gion et \u00e0 intervenir militairement pour emp\u00eacher le d\u00e9veloppement de puissances r\u00e9gionales antisionistes. L\u2019Afghanistan et l\u2019Irak furent les premi\u00e8res victimes de cette politique. Aujourd\u2019hui, les alliances sont claires. L\u2019Arabie Saoudite et le Qatar se positionnent clairement dans le camp imp\u00e9rialiste en organisant la contre-r\u00e9volution. Dans le contexte des mouvements populaires dans le Monde arabe, les r\u00e9actions de l\u2019Occident sont dict\u00e9es par les int\u00e9r\u00eats sionistes. Tunisie, Egypte, Libye, Syrie, un seul objectif pour l\u2019Occident : emp\u00eacher la g\u00e9n\u00e9ralisation d\u2019un mouvement de masse d\u2019\u00e9mancipation et de r\u00e9sistance au sionisme.<\/p>\n<p style=\"text-align: justify\">Dans les pays occidentaux, et notamment en France qui collabore activement avec Isra\u00ebl toute critique et remise en question de l\u2019entit\u00e9 sioniste sont syst\u00e9matiquement soumises \u00e0 censure et \u00e0 accusation d\u2019antis\u00e9mitisme. Quand il s\u2019agit d\u2019Isra\u00ebl, la libert\u00e9 d\u2019expression est bafou\u00e9e, alors qu\u2019elle est d\u00e9fendue en principe par toute l\u2019intelligentsia et la classe politique dans d\u2019autres circonstances. Le CRIF ne rel\u00e2che pas ses efforts pour faire interdire des conf\u00e9rences et intenter des proc\u00e8s contre tous ceux qui osent r\u00e9sister au sionisme. Pourtant l\u2019antisionisme n\u2019est pas un crime. Il est une exigence de justice. La population fran\u00e7aise ne doit pas se laisser intimider par le fascisme rampant qui gagne du terrain. Il est plus que jamais n\u00e9cessaire de se mobiliser pour d\u00e9noncer \u00e0 la fois l\u2019Etat sioniste et la classe politique fran\u00e7aise qui collabore avec lui.<\/p>\n<p style=\"text-align: justify\"><strong>Les conf\u00e9renciers traiteront de ces questions. Jean Bricmont est professeur de physique \u00e0 l&rsquo;Universit\u00e9 de Louvain (Belgique) et ardent d\u00e9fenseur de la libert\u00e9 d&rsquo;expression, notamment en lien avec le sionisme. Omar Mazri est ing\u00e9nieur sp\u00e9cialis\u00e9 en hautes technologies et \u00e9conomiste, il a \u00e9crit de nombreux ouvrages sur l&rsquo;islam, le monde arabe et les r\u00e9volutions. Nous vous invitons \u00e0 venir \u00e9changer avec eux.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comit\u00e9\u00a0Action\u00a0Palestine \u00a0 \u00a0A l\u2019occasion de la Journ\u00e9e de la terre\u00a0en Palestine, \u00a0 \u00a0\u00ab\u00a0R\u00e9sister au sionisme\u00a0\u00bb \u00a0 Conf\u00e9rences-d\u00e9bats avec \u00a0 \u00a0Jean Bricmont, \u00a0\u00ab\u00a0R\u00e9sister au sionisme : d\u00e9fendre la libert\u00e9 d&rsquo;expression\u00a0\u00bb le 23 mars 20h30, Ath\u00e9n\u00e9e Municipal, Bordeaux (Tram A et B, arr\u00eat H\u00f4tel de Ville) \u00a0 Omar Mazri, \u00a0\u00ab\u00a0R\u00e9volutions et contre-r\u00e9volution dans le monde arabe\u00a0\u00bb le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1622","post","type-post","status-publish","format-standard","hentry","category-actions"],"views":2860,"_links":{"self":[{"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/comments?post=1622"}],"version-history":[{"count":2,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1622\/revisions"}],"predecessor-version":[{"id":1624,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1622\/revisions\/1624"}],"wp:attachment":[{"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/media?parent=1622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/categories?post=1622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/tags?post=1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}