{"id":1710,"date":"2006-10-18T11:20:27","date_gmt":"2006-10-18T10:20:27","guid":{"rendered":"http:\/\/www.comiteactionpalestine.org\/word\/?p=1710"},"modified":"2014-05-02T21:33:12","modified_gmt":"2014-05-02T20:33:12","slug":"au-dela-de-toute-comparaison","status":"publish","type":"post","link":"http:\/\/www.comiteactionpalestine.org\/word\/au-dela-de-toute-comparaison\/","title":{"rendered":"Au del\u00e0 de toute comparaison"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1710?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\" \/><\/a><a href=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1710?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><p align=\"justify\"><a href=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-content\/uploads\/2006\/10\/Jews_israel_nazi1.jpg\"><img decoding=\"async\" class=\"alignright  wp-image-1964\" src=\"http:\/\/www.comiteactionpalestine.org\/word\/wp-content\/uploads\/2006\/10\/Jews_israel_nazi1.jpg\" alt=\"Jews_israel_nazi[1]\" width=\"238\" height=\"154\" \/><\/a>Article de <strong>Gilad Atzmon<\/strong> du 10 ao\u00fbt 2006<\/p>\n<p align=\"justify\">Traduit de l&rsquo;anglais par M. Charbonnier et r\u00e9vis\u00e9 par F. Giudice, membres de Tlaxcala <a href=\"http:\/\/www.tlaxcala.es\/\" target=\"_blank\">www.tlaxcala.es<\/a><a href=\"http:\/\/www.tlaxcala.es\/\" target=\"_blank\"> r\u00e9seau de traducteurs pour la diversit\u00e9 liguistique. <\/a><\/p>\n<p>L&rsquo;auteur est un musicien de Jazz, n\u00e9 en Isra\u00ebl en 1963 et exil\u00e9 en Angleterre. Il a derni\u00e8rement compos\u00e9 la musique du dernier documentaire de Simone Bitton \u00ab\u00a0Le mur\u00a0\u00bb qui a obtenu le Grand Prix du Festival international du documentaire de Marseille 2004.<\/p>\n<hr \/>\n<p style=\"text-align: left;\" align=\"right\">\n<p align=\"right\"><em>\u00ab L\u2019action militaire isra\u00e9lienne est une agression injustifi\u00e9e, effectu\u00e9e dans un style digne d\u2019Hitler, d\u2019une mani\u00e8re fasciste. \u00bb <\/em><strong>Hugo Ch\u00e1vez<\/strong> , Pr\u00e9sident de la R\u00e9publique bolivarienne du Venezuela<\/p>\n<p align=\"right\"><em>\u00ab A l\u2019\u00e9vidence, le Pr\u00e9sident Ch\u00e1vez a bien besoin de reprendre contact avec la r\u00e9alit\u00e9 en ce qui concerne le conflit au Moyen-Orient. \u00bb <\/em><strong>Abraham H. Foxman<\/strong> , Directeur national (pour les USA)de l\u2019Anti-Defamation League<\/p>\n<p>&nbsp;<\/p>\n<p align=\"justify\">Il y a incontestablement une tendance, chez nous tous \u2013 nous, les d\u00e9tracteurs d\u2019Isra\u00ebl et du sionisme. A tout bout de champ, nous comparons Isra\u00ebl au Troisi\u00e8me Reich ; nous identifions l\u2019arm\u00e9e isra\u00e9lienne \u2013 \u00ab Tsahal \u00bb \u2013 \u00e0 la Wehrmacht ; nous trouvons une ressemblance entre les tactiques de l\u2019aviation isra\u00e9lienne et les techniques du blitz de la Luftwaffe ; \u00e0 l\u2019occasion, nous associons les crimes de guerre de Sharon et d\u2019Olmert \u00e0 ceux d\u2019Hitler. Je suis moi-m\u00eame tomb\u00e9 dans ce pi\u00e8ge, t\u00eate la premi\u00e8re, \u00e0 maintes reprises. Mais maintenant, \u00e7a y est, j\u2019ai r\u00e9agi : il faut qu\u2019un terme soit mis \u00e0 cette mani\u00e8re de s\u2019exprimer, une bonne fois pour toutes !<\/p>\n<p align=\"justify\">Voir en Hitler le Mal absolu, cela revient tout simplement \u00e0 capituler devant le discours siono-centriste. Consid\u00e9rer Hitler comme l\u2019homme le plus perfide et le Troisi\u00e8me Reich comme l\u2019incarnation du mal, cela n\u2019a d\u2019autre r\u00e9sultat que de sauver la mise \u00e0 Isra\u00ebl. Comparer Olmert \u00e0 Hitler, cela revient \u00e0 fournir \u00e0 Isra\u00ebl et \u00e0 Olmert un bouclier moral. Cela maintient Hitler en t\u00eate du peloton, et cela permet \u00e0 Olmert de se planquer juste devant la voiture balai.<\/p>\n<p align=\"justify\">Ma m\u00e8re, qui est vraiment tr\u00e8s clairvoyante, m\u2019a coinc\u00e9, un jour, il y a de cela bien des ann\u00e9es\u2026 Je m\u2019en souviens tr\u00e8s bien. Elle m\u2019a demand\u00e9 : \u00ab Dis-moi, Gilad, pourquoi diable, tes amis et toi, vous \u00e9prouvez toujours ce besoin de comparer Isra\u00ebl aux Nazis ? Isra\u00ebl n\u2019est pas assez horrible sans cela ? \u00bb<\/p>\n<p align=\"justify\">Sur le coup, j\u2019ai trouv\u00e9 son observation plut\u00f4t amusante, mais l\u2019intuition cynique de ma m\u00e8re \u00e9tait tout \u00e0 fait pertinente. En effet, Isra\u00ebl est \u00ab assez horrible comme \u00e7a \u00bb.<\/p>\n<p align=\"justify\">Isra\u00ebl a d\u2019ores et d\u00e9j\u00e0 d\u00e9montr\u00e9 une interpr\u00e9tation unique en son genre de la notion de rouerie qui a r\u00e9ussi \u00e0 surpasser tout autre mal. Il est grand temps que nous int\u00e9grions le fait qu\u2019Isra\u00ebl et le sionisme sont le Mal absolu, sans aucun point de comparaison. Et si cela ne suffisait pas, rappelons que, contrairement au nazisme, qui appartient au pass\u00e9, la malignit\u00e9 du sionisme est un crime qui continue \u00e0 se d\u00e9rouler, en empirant. Ch\u00e1vez avait, de toute \u00e9vidence, le droit le plus absolu de d\u00e9clarer ce qu\u2019il a d\u00e9clar\u00e9. Cependant, que l\u2019adorable pr\u00e9sident du Venezuela me permette de lui rappeler qu\u2019Hitler n\u2019a jamais d\u00e9truit par bombardements un quelconque pays en l\u2019absence d\u2019un quelconque motif. Or, c\u2019est exactement ce que les Isra\u00e9liens sont en train de faire depuis quatre semaines au Liban, et c\u2019est ce qu\u2019ils font, depuis des ann\u00e9es et des ann\u00e9es, \u00e0 Gaza. Le spectacle du carnage et de la d\u00e9vastation au Liban ne laisse aucune place au doute. La brutalit\u00e9 isra\u00e9lienne actuelle n\u2019est rien d\u2019autre que le mal pour le mal, une punition impitoyable. Isra\u00ebl est une r\u00e9incarnation collective d\u00e9vastatrice du Samson de la Bible. Isra\u00ebl est une r\u00e9\u00e9dition de l\u2019homme tuant femmes, enfants et vieillards, c\u2019est ce ma\u00eetre victorieux des repr\u00e9sailles aveugles et arbitraires, tellement r\u00e9current dans la Bible [que cela en devient lassant].<\/p>\n<p align=\"justify\">Depuis de longues ann\u00e9es, les progressistes politiquement corrects qui se pr\u00e9sentent eux-m\u00eames comme de gauche insistent \u00e0 nous raconter que l\u2019agression isra\u00e9lienne doit \u00eatre analys\u00e9e en termes d\u2019expansionnisme colonial. Cette ligne de pens\u00e9e continue \u00e0 \u00eatre propag\u00e9e par quelques militants pacifistes juifs, un peu partout dans le monde. La raison est simple : aussi longtemps qu\u2019Isra\u00ebl continuera \u00e0 \u00eatre consid\u00e9r\u00e9 comme un \u00c9tat colonial, ils pourront continuer \u00e0 appliquer au conflit moyen-oriental leur paradigme marxiste orthodoxe archa\u00efque \u2013 remontant au dix-neuvi\u00e8me si\u00e8cle. De plus, si Isra\u00ebl \u00e9tait bien effectivement une force coloniale r\u00e9gionale expansionniste, alors il n\u2019y aurait rien de cat\u00e9goriquement mauvais, chez les Isra\u00e9liens ; ils seraient tout simplement comme l\u2019\u00e9taient les Britanniques, avec un petit demi-si\u00e8cle de retard, voil\u00e0 tout\u2026<\/p>\n<p align=\"justify\">D\u00e9lirant ! L\u2019interpr\u00e9tation surann\u00e9e que nous venons d\u2019\u00e9voquer est fondamentalement erron\u00e9e et d\u00e9lib\u00e9r\u00e9ment trompeuse. De plus, elle n\u2019est plus applicable, m\u00eame plus en tant que feuille de vigne \u00e0 usage d\u2019un \u00ab politiquement correct \u00bb jud\u00e9ocentrique. Il suffit de regarder la d\u00e9vastation sem\u00e9e par l\u2019aviation de guerre isra\u00e9lienne, de contempler la mort et le carnage au Liban : il n\u2019y a plus l\u2019ombre d\u2019un doute, ce qui est en train de se passer n\u2019a strictement rien \u00e0 voir ni avec le colonialisme, ni avec l\u2019expansionnisme. Le Liban et Beyrouth n\u2019ont jamais fait partie des aspirations au Lebensraum des sionistes. C\u2019est exactement le contraire qui est vrai : jusqu\u2019\u00e0 la fin des ann\u00e9es 1960, les Isra\u00e9liens \u00e9taient absolument persuad\u00e9s que le Liban serait le premier pays arabe \u00e0 faire la paix avec l\u2019\u00c9tat juif. Isra\u00ebl n\u2019a jamais eu aucune vis\u00e9e sur le territoire situ\u00e9 au Nord de la rivi\u00e8re Litani et, malgr\u00e9 cela, Isra\u00ebl a d\u00e9sormais d\u00e9truit absolument tous les ponts, tous les a\u00e9roports, toutes les stations \u00e9lectriques du Liban. Les h\u00f4pitaux sont bombard\u00e9s, des villages et des quartiers entiers ont \u00e9t\u00e9 ray\u00e9s de la carte, un millier de civils libanais ont perdu la vie et plus d\u2019un million de citoyens libanais sont d\u00e9plac\u00e9s et sans abri.<\/p>\n<p align=\"justify\">Maintenant, \u00e7a suffit : il faut se lever et dire qu\u2019\u00e0 la diff\u00e9rence des Nazis, qui respectaient les autres mouvements nationalistes \u2013 y compris le sionisme \u2013 Isra\u00ebl n\u2019a strictement aucun respect pour quiconque, y compris ses voisins de palier. Il faut prendre conscience du fait que le comportement isra\u00e9lien est le summum de la barbarie biblique, apr\u00e8s lequel il n\u2019y a plus que le cannibalisme. Isra\u00ebl n\u2019est rien d\u2019autre que le mal pour l\u2019amour du mal. C\u2019est une perversion sans aucune comparaison.<\/p>\n<p align=\"justify\">D\u00e8s lors, entre Isra\u00ebl et les Nazis, il n\u2019existe plus la moindre diff\u00e9rence qui permettrait de proc\u00e9der, \u00e0 proprement parler, \u00e0 une comparaison. Et si comparaison il devait y avoir, ce serait alors les Isra\u00e9liens qui remporterait le championnat de la brutalit\u00e9, pour des raisons \u00e9videntes. L\u2019Allemagne nazie \u00e9tait une tyrannie, alors qu\u2019Isra\u00ebl est une d\u00e9mocratie, gouvern\u00e9e par un gouvernement d\u2019union nationale majoritairement de centre gauche. Si nous n\u2019avons \u00e0 notre disposition aucun instrument objectif pr\u00e9cis permettant de mesurer l\u2019approbation des crimes nazis par le peuple allemand (pour commencer, les Allemands n\u2019\u00e9taient pas inform\u00e9s des crimes homicides nazis. Ensuite, il n\u2019existait en Allemagne, \u00e0 l\u2019\u00e9poque, aucun organisme de sondage ind\u00e9pendant), la population isra\u00e9lienne, elle, approuve collectivement les crimes de son gouvernement au Liban, et ce fait est surabondamment attest\u00e9 par une foultitude de sondages.<\/p>\n<p align=\"justify\">Les nazis \u00e9taient certes des expansionnistes au sens propre du terme : ils s\u2019effor\u00e7aient de s\u2019emparer de villes et de territoires intacts.<\/p>\n<p align=\"justify\">Les bombardements en tapis et la destruction de quartiers entiers dens\u00e9ment peupl\u00e9s, tellement tendance chez les militaires et les hommes politiques isra\u00e9liens (ainsi qu\u2019anglo-am\u00e9ricains), cela n\u2019a jamais fait partie de la tactique, ni de la strat\u00e9gie des Nazis. Apparemment, Isra\u00ebl ne cherche pas \u00e0 s\u2019emparer du Liban ; les Isra\u00e9liens ne semblent pas \u00eatre int\u00e9ress\u00e9s par le territoire libanais. Non : tout ce qu\u2019ils veulent, c\u2019est d\u00e9molir le Liban ! On peut se perdre en conjectures sur ce qu\u2019ils cherchent v\u00e9ritablement ? De fait, personne, ni en Isra\u00ebl, ni o\u00f9 que ce soit ailleurs, du reste, ne le sait.<\/p>\n<p align=\"justify\">Veulent-ils d\u00e9manteler le Hezbollah ? Assur\u00e9ment, ils ont r\u00e9ussi \u00e0 faire exactement le contraire ! Leur impression que le Hezbollah ne serait qu\u2019une petite faction de miliciens fondamentalistes minoritaires du point de vue religieux et qu\u2019on aurait pu \u00e9liminer sans effort notable s\u2019av\u00e8re \u00eatre une th\u00e8se ridicule, et cela est confirm\u00e9 \u00e0 chaque jour qui passe. Non seulement le Hezbollah a d\u00e9montr\u00e9 qu\u2019il est une force avec laquelle il faudra compter, mais il est aujourd\u2019hui soutenu par 85 % des Libanais, y compris chez les chr\u00e9tiens [dont 80 % soutiennent le Hezbollah .]<\/p>\n<p align=\"justify\">Isra\u00ebl veut-il conserver sa puissance de dissuasion ? L\u00e0 encore, il a r\u00e9ussi \u00e0 faire exactement le contraire. D\u00e9sormais, tout Arabe sait que l\u2019arm\u00e9e isra\u00e9lienne n\u2019est plus si formidable et glorieuse que \u00e7a. De fait, les photos des godillots de soldats isra\u00e9liens abandonn\u00e9s sur le sol libanais en disent tr\u00e8s long. Dans cette guerre, c\u2019est le soldat isra\u00e9lien qui se d\u00e9barrasse de ses rangers pour pouvoir courir plus vite tenter de sauver sa peau.<\/p>\n<p align=\"justify\">Isra\u00ebl veut-il assurer la s\u00e9curit\u00e9 de ses centres peupl\u00e9s ? Il a, de toute \u00e9vidence, r\u00e9ussi \u00e0 faire exactement le contraire. Plus Isra\u00ebl d\u00e9truit l\u2019infrastructure du Liban, plus sont intenses les tirs de barrage de roquettes qui s\u2019abattent sur les villes isra\u00e9liennes. De fait, le moment o\u00f9 Tel Aviv pourra se faire une petite id\u00e9e de ce \u00e0 quoi ressemble la vie \u00e0 Gaza et \u00e0 Beyrouth n\u2019est plus qu\u2019une question de temps. Oui, c\u2019est un fait : Isra\u00ebl n\u2019a ni plan, ni strat\u00e9gie ; en lieu et place, il pratique la forme la plus vile de z\u00e8le barbare collectif. Les Isra\u00e9liens d\u00e9molissent pour le plaisir de d\u00e9truire. Isra\u00ebl est bien, en effet, un mal incomparable.<\/p>\n<p align=\"justify\">N\u00e9anmoins, force nous est bien d\u2019admettre que les Nazis ont eu un succ\u00e8s assez remarquable pour ce qui est de provoquer un certaine outrage international. En-dehors du monde germanique [et de l\u2019aristocratie britannique, ne l\u2019oublions pas\u2026], peu de gens aimaient Hitler.<\/p>\n<p align=\"justify\">En revanche, le cannibalisme isra\u00e9lien est absolument adul\u00e9 par certains dirigeants occidentaux, et ce sont Blair, Bush et m\u00eame Merkel qui ont trop peur pour s\u2019opposer \u00e0 la barbarie sioniste. Alors que le nazisme a \u00e9t\u00e9 vaincu douze ans apr\u00e8s son accession au pouvoir, la brutalit\u00e9 sioniste est une boule de neige d\u2019une haine repoussante, qui ne conna\u00eet ni limites ni fin. Cette boule de neige de haine roule sur l\u2019Occident, y recrutant les forces les plus d\u00e9t\u00e9rior\u00e9es sur le plan moral qu\u2019elle y rencontre sur son passage, qu\u2019il s\u2019agisse de Blair et de son engeance ou de fondamentalistes chr\u00e9tiens extr\u00e9mistes am\u00e9ricains. Le sionisme vise \u00e0 faire de notre Plan\u00e8te un champ de bataille ensanglant\u00e9. Pour le moment, il est en train de transformer les institutions de l\u2019Onu en une marionnette n\u00e9oconservatrice am\u00e9ricaine.<\/p>\n<p align=\"justify\">Il est grand temps de reconna\u00eetre que les sionistes sont au centre m\u00eame de ce qu\u2019on appelle le \u00ab clash entre cultures \u00bb.<\/p>\n<p align=\"justify\">Alors que le Nazisme \u00e9tait un mouvement nationaliste expansionniste aux ambitions extensives, mais n\u00e9anmoins limit\u00e9es, les lobbies sioniste et isra\u00e9lien tentent de remettre au go\u00fbt du jour l\u2019id\u00e9e d\u2019une croisade plan\u00e9taire, au nom d\u2019une guerre de religion tr\u00e8s bizarre (cens\u00e9e opposer on ne sait trop quels \u00ab jud\u00e9o-chr\u00e9tiens \u00bb aux musulmans). Si nous voulons sauver le monde, si nous voulons vivre sur une plan\u00e8te humaine, nous devons nous concentrer sur le pire ennemi de la paix, sur ces ennemis qui sont rou\u00e9s pour le plaisir de faire le mal : j\u2019ai nomm\u00e9 l\u2019\u00c9tat d\u2019Isra\u00ebl et le sionisme mondial.<\/p>\n<p align=\"justify\">Il est plus que temps de sortir du placard et de dire tout cela, et \u00e0 haute et intelligible voix. Isra\u00ebl et le sionisme mettent le monde en danger. Ce ne sont pas \u00ab seulement \u00bb le Liban, la Palestine et les Arabes, qui souffrent. C\u2019est d\u00e9sormais la Grande-Bretagne et l\u2019Am\u00e9rique qui sont entra\u00een\u00e9es dans une guerre stupide. C\u2019est l\u2019ensemble de l\u2019Occident qui se voit somm\u00e9 de tenter de sauver ce que les Isra\u00e9liens n\u2019ont pas fini de bousiller au Liban.<\/p>\n<p align=\"justify\">Nous devons tous nous d\u00e9-sioniser, tant qu\u2019il en est encore temps !<\/p>\n<p align=\"justify\">Nous devons comprendre que c\u2019est Isra\u00ebl qui incarne le Mal absolu, et non pas l\u2019Allemagne nazie. Abe Foxman et l\u2019Anti-Defamation League ont raison \u2013 une fois n\u2019est pas coutume : nous avons tous besoin de reprendre contact avec la r\u00e9alit\u00e9.<\/p>\n<p align=\"justify\">Nous ne devrions plus jamais comparer Isra\u00ebl \u00e0 l\u2019Allemagne nazie.<\/p>\n<p align=\"justify\">Dans la course \u00e0 l\u2019horreur, nous devons d\u00e9sormais laisser Isra\u00ebl prendre la t\u00eate du peloton, et la conserver\u2026<\/p>\n<p align=\"justify\">Sources :<br \/>\nArticle original sur le <a href=\"http:\/\/www.gilad.co.uk\/\">site de Gilad Atzmon<\/a><br \/>\nTraduction de Marcel Charbonnier, r\u00e9vis\u00e9e par Fausto Giudice, <a href=\"http:\/\/www.tlaxcala.es\/pp.asp?lg=fr&amp;reference=1277\" target=\"_blank\">sur le site de Tlaxcala<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Article de Gilad Atzmon du 10 ao\u00fbt 2006 Traduit de l&rsquo;anglais par M. Charbonnier et r\u00e9vis\u00e9 par F. Giudice, membres de Tlaxcala www.tlaxcala.es r\u00e9seau de traducteurs pour la diversit\u00e9 liguistique. L&rsquo;auteur est un musicien de Jazz, n\u00e9 en Isra\u00ebl en 1963 et exil\u00e9 en Angleterre. Il a derni\u00e8rement compos\u00e9 la musique du dernier documentaire de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1710","post","type-post","status-publish","format-standard","hentry","category-sionisme-dans-le-monde"],"views":2596,"_links":{"self":[{"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/comments?post=1710"}],"version-history":[{"count":3,"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1710\/revisions"}],"predecessor-version":[{"id":1965,"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/posts\/1710\/revisions\/1965"}],"wp:attachment":[{"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/media?parent=1710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/categories?post=1710"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.comiteactionpalestine.org\/word\/wp-json\/wp\/v2\/tags?post=1710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}